{"id":1056,"date":"2021-09-04T13:05:35","date_gmt":"2021-09-04T13:05:35","guid":{"rendered":"https:\/\/bslthemes.com\/tastyc\/fullwidth\/?page_id=1056"},"modified":"2021-09-04T13:05:35","modified_gmt":"2021-09-04T13:05:35","slug":"reservation-opentable","status":"publish","type":"page","link":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/reservation-opentable\/","title":{"rendered":"Reservation (OpenTable)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1056\" class=\"elementor elementor-1056\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28ec997 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"28ec997\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fcce476\" data-id=\"fcce476\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a37e7d elementor-widget elementor-widget-tastyc-reservation-form\" data-id=\"3a37e7d\" data-element_type=\"widget\" data-widget_type=\"tastyc-reservation-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<!-- container -->\n\t\t<div class=\"container\">\n\n\t\t\t<div class=\"row\">\n\n\t\t\t                <div class=\"col-lg-12\">\n                <!-- title -->\n                <div class=\"text-center\">\n                                    <div class=\"tst-suptitle tst-suptitle-center tst-mb-15\">\n                  \t<span >\n\t\t\t          \tReservation\t\t\t        <\/span>\n                  <\/div>\n                                                      <h3 class=\"tst-title--h tst-mb-30\">\n                  \t<span >\n\t\t\t          \tBook a Table\t\t\t        <\/span>\n                  <\/h3>\n                                                      <p class=\"tst-text tst-mb-60\">\n                  \t<span >\n\t\t\t          \tCALL US +1 777 000 111 OR COMPLETE THE FORM BELOW\t\t\t        <\/span>\n                  <\/p>\n                                  <\/div>\n                <!-- title end -->\n              <\/div>\n          \t  \n          \t  \t          \t  \t              <div class=\"col-lg-12\">\n\t                <form method=\"get\" class=\"tst-opentable-form\" action=\"\/\/www.opentable.com\/restaurant-search.aspx\" target=\"_blank\">\n\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t  <div class=\"col-12 col-md-4\">\n\t\t\t\t\t\t    <select id=\"reservation_party\" name=\"partySize\">\n\t\t\t\t\t\t\t\t<option value=\"1\">1 Person<\/option>\n\t\t\t\t\t\t\t\t<option value=\"2\" selected=\"selected\">2 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"3\">3 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"4\">4 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"5\">5 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"6\">6 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"7\">7 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"8\">8 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"9\">9 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"10\">10 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"11\">11 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"12\">12 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"13\">13 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"14\">14 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"15\">15 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"16\">16 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"17\">17 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"18\">18 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"19\">19 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"20\">20 People<\/option>\n\t\t\t\t\t\t\t\t<option value=\"21\">Larger party<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"col-12 col-md-4\">\n\t\t\t\t\t\t    <div class=\"datepicker__container\">\n\t\t\t\t\t\t      <input id=\"reservation_date\" name=\"startDate\" class=\"datepicker-here\" type=\"text\" value=\"\" placeholder=\"Date\" autocomplete=\"off\" readonly=\"readonly\">\n\t\t\t\t\t\t    <\/div>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"col-12 col-md-4\">\n\t\t\t\t\t\t    <select id=\"reservation_time\" name=\"ResTime\">\n\t\t\t\t\t\t\t\t<option value=\"8:00am\" >8:00 am<\/option>\n<option value=\"8:30am\" >8:30 am<\/option>\n<option value=\"9:00am\" >9:00 am<\/option>\n<option value=\"9:30am\" >9:30 am<\/option>\n<option value=\"10:00am\" >10:00 am<\/option>\n<option value=\"10:30am\" >10:30 am<\/option>\n<option value=\"11:00am\" >11:00 am<\/option>\n<option value=\"11:30am\" >11:30 am<\/option>\n<option value=\"12:00pm\" >12:00 pm<\/option>\n<option value=\"12:30pm\" >12:30 pm<\/option>\n<option value=\"1:00pm\" >1:00 pm<\/option>\n<option value=\"1:30pm\" >1:30 pm<\/option>\n<option value=\"2:00pm\" >2:00 pm<\/option>\n<option value=\"2:30pm\" >2:30 pm<\/option>\n<option value=\"3:00pm\" >3:00 pm<\/option>\n<option value=\"3:30pm\" >3:30 pm<\/option>\n<option value=\"4:00pm\" >4:00 pm<\/option>\n<option value=\"4:30pm\" >4:30 pm<\/option>\n<option value=\"5:00pm\" >5:00 pm<\/option>\n<option value=\"5:30pm\" >5:30 pm<\/option>\n<option value=\"6:00pm\" >6:00 pm<\/option>\n<option value=\"6:30pm\" >6:30 pm<\/option>\n<option value=\"7:00pm\"  selected=\"selected\" >7:00 pm<\/option>\n<option value=\"7:30pm\" >7:30 pm<\/option>\n<option value=\"8:00pm\" >8:00 pm<\/option>\n<option value=\"8:30pm\" >8:30 pm<\/option>\n<option value=\"9:00pm\" >9:00 pm<\/option>\n<option value=\"9:30pm\" >9:30 pm<\/option>\n<option value=\"10:00pm\" >10:00 pm<\/option>\n<option value=\"10:30pm\" >10:30 pm<\/option>\n<option value=\"11:00pm\" >11:00 pm<\/option>\n<option value=\"11:30pm\" >11:30 pm<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"text-center\">\n\t\t\t\t\t\t\t<button class=\"tst-btn\" type=\"submit\" name=\"button\">Reserve a table<\/button>\n\t\t\t\t\t\t\t<p class=\"tst-powered d-center tst-p-15-0\">* Powered by <img decoding=\"async\" src=\"https:\/\/determined-cannon.95-216-35-79.plesk.page\/wp-content\/themes\/tastyc\/assets\/images\/opentable.svg\" alt=\"\" \/><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" name=\"RestaurantID\" class=\"RestaurantID\" value=\"412810\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"rid\" class=\"rid\" value=\"412810\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"GeoID\" class=\"GeoID\" value=\"15\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"txtDateFormat\" class=\"txtDateFormat\" value=\"MM\/dd\/yyyy\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"RestaurantReferralID\" class=\"RestaurantReferralID\" value=\"412810\">\n\t\t\t\t\t\t<input type=\"hidden\" name=\"lang\" class=\"lang\" value=\"en-US\">\n\t\t\t\t\t<\/form>\n\t              <\/div>\n\t              \t          \n            <\/div>\n\n        <\/div>\n\n\t\t<!-- container end -->\t\t\t\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bce9408 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bce9408\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba0fba4\" data-id=\"ba0fba4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79b8352 elementor-widget elementor-widget-tastyc-section-divider\" data-id=\"79b8352\" data-element_type=\"widget\" data-widget_type=\"tastyc-section-divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"tst-spacer \"><\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c14f33 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1c14f33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db5c749\" data-id=\"db5c749\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2642bfc elementor-widget elementor-widget-tastyc-services\" data-id=\"2642bfc\" data-element_type=\"widget\" data-widget_type=\"tastyc-services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<!-- container -->\n\t\t<div class=\"container\">\n\n\t\t<div class=\"row\">\n\t\t            <div class=\"col-lg-12\">\n\n            <!-- title -->\n            <div class=\"text-center\">\n                            <div class=\"tst-suptitle tst-suptitle-center tst-mb-15\">\n              \t<span >\n\t\t          \thave a questions?\t\t        <\/span>\n              <\/div>\n                                          <h4 class=\"tst-title--h tst-mb-30\">\n              \t<span >\n\t\t          \tContact Us\t\t        <\/span>\n              <\/h4>\n                                          <p class=\"tst-text tst-title--desc tst-mb-60\">\n              \t<span >\n\t\t          \tQuaerat debitis, vel, sapiente dicta sequi\nlabore porro pariatur harum expedita.\t\t        <\/span>\n              <\/p>\n                          <\/div>\n            <!-- title end -->\n\n          <\/div>\n          \n          \t\t            <div class=\"col-lg-4\">\n\n            <!-- icon box -->\n            <div class=\"tst-icon-box tst-mb-60\">\n                            <img decoding=\"async\" src=\"https:\/\/determined-cannon.95-216-35-79.plesk.page\/wp-content\/uploads\/2021\/04\/icon-contact-email-256x256.png\" alt=\"\" class=\"tst-mb-30\" \/>\n                                          <h5 class=\"tst-mb-30\">\n              \t<span >\n\t        \t\tEmail\t        \t<\/span>\n              <\/h5>\n                                          <div class=\"tst-text\">\n              \t<div >\n\t        \t\t<p><a href=\"mailto:info@tastyc.com\">info@tastyc.com<\/a><br \/><a href=\"mailto:reservation@tastyc.com\">reservation@tastyc.com<\/a><\/p>\t        \t<\/div>\n              <\/div>\n                          <\/div>\n            <!-- icon box end -->\n\n          <\/div>\n                    <div class=\"col-lg-4\">\n\n            <!-- icon box -->\n            <div class=\"tst-icon-box tst-mb-60\">\n                            <img decoding=\"async\" src=\"https:\/\/determined-cannon.95-216-35-79.plesk.page\/wp-content\/uploads\/2021\/04\/icon-contact-tel-256x256.png\" alt=\"\" class=\"tst-mb-30\" \/>\n                                          <h5 class=\"tst-mb-30\">\n              \t<span >\n\t        \t\tPhone\t        \t<\/span>\n              <\/h5>\n                                          <div class=\"tst-text\">\n              \t<div >\n\t        \t\t<a href=\"tel:+760947544371\">+76 (094) 754 43 71<\/a><br>\n<a href=\"tel:+760937534372\">+76 (093) 753 43 72<\/a>\t        \t<\/div>\n              <\/div>\n                          <\/div>\n            <!-- icon box end -->\n\n          <\/div>\n                    <div class=\"col-lg-4\">\n\n            <!-- icon box -->\n            <div class=\"tst-icon-box tst-mb-60\">\n                            <img decoding=\"async\" src=\"https:\/\/determined-cannon.95-216-35-79.plesk.page\/wp-content\/uploads\/2021\/04\/icon-contact-adr-256x256.png\" alt=\"\" class=\"tst-mb-30\" \/>\n                                          <h5 class=\"tst-mb-30\">\n              \t<span >\n\t        \t\tLocation\t        \t<\/span>\n              <\/h5>\n                                          <div class=\"tst-text\">\n              \t<div >\n\t        \t\t<p>Canada, Toronto, North Avenue 31B<\/p>\t        \t<\/div>\n              <\/div>\n                          <\/div>\n            <!-- icon box end -->\n\n          <\/div>\n                    \n        <\/div>\n\n        <div class=\"tst-spacer tst-spacer-only-bottom-space\"><\/div>\n\n\t\t<\/div>\n\t\t<!-- container end -->\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Reservation Book a Table CALL US +1 777 000 111 OR COMPLETE THE FORM BELOW 1 Person2 People3 People4 People5&#8230; <span class=\"tst-el-more\"><a href=\"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/reservation-opentable\/\" class=\"tst-label tst-color tst-anima-link\">Read more<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-layout-builder.php","meta":{"footnotes":""},"class_list":["post-1056","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/1056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/comments?post=1056"}],"version-history":[{"count":0,"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/1056\/revisions"}],"wp:attachment":[{"href":"https:\/\/determined-cannon.95-216-35-79.plesk.page\/index.php\/wp-json\/wp\/v2\/media?parent=1056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}